{"id":1539,"date":"2024-12-03T14:25:37","date_gmt":"2024-12-03T13:25:37","guid":{"rendered":"https:\/\/danselibremalkovsky.com\/?post_type=exercice&#038;p=1539"},"modified":"2025-02-20T11:43:04","modified_gmt":"2025-02-20T10:43:04","slug":"loiseau-en-sautant-dans-la-corde","status":"publish","type":"exercice","link":"https:\/\/danselibremalkovsky.com\/es\/exercice\/loiseau-en-sautant-dans-la-corde\/","title":{"rendered":"El p\u00e1jaro - Saltando en la cuerda"},"excerpt":{"rendered":"","protected":false},"featured_media":1541,"parent":0,"template":"","meta":{"_acf_changed":false,"pmpro_default_level":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categorie":[20],"class_list":["post-1539","exercice","type-exercice","status-publish","has-post-thumbnail","hentry","categorie-loiseau","pmpro-has-access"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;oiseau - en sautant dans la corde - danselibremalkovsky.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/danselibremalkovsky.com\/es\/exercice\/loiseau-en-sautant-dans-la-corde\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;oiseau - en sautant dans la corde - danselibremalkovsky.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/danselibremalkovsky.com\/es\/exercice\/loiseau-en-sautant-dans-la-corde\/\" \/>\n<meta property=\"og:site_name\" content=\"danselibremalkovsky.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T10:43:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/12\/L_oiseau-en-sautant-dans-la-corde.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/\",\"url\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/\",\"name\":\"L'oiseau - en sautant dans la corde - danselibremalkovsky.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/danselibremalkovsky.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/L_oiseau-en-sautant-dans-la-corde.png\",\"datePublished\":\"2024-12-03T13:25:37+00:00\",\"dateModified\":\"2025-02-20T10:43:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/danselibremalkovsky.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/L_oiseau-en-sautant-dans-la-corde.png\",\"contentUrl\":\"https:\\\/\\\/danselibremalkovsky.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/L_oiseau-en-sautant-dans-la-corde.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/exercice\\\/loiseau-en-sautant-dans-la-corde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/danselibremalkovsky.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;oiseau &#8211; en sautant dans la corde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/#website\",\"url\":\"https:\\\/\\\/danselibremalkovsky.com\\\/\",\"name\":\"danselibremalkovsky.com\",\"description\":\"&quot;Entrez dans la danse...&quot;\",\"publisher\":{\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/danselibremalkovsky.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/#organization\",\"name\":\"danselibremalkovsky.com\",\"url\":\"https:\\\/\\\/danselibremalkovsky.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/danselibremalkovsky.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-Callian_logo.png\",\"contentUrl\":\"https:\\\/\\\/danselibremalkovsky.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-Callian_logo.png\",\"width\":1406,\"height\":1685,\"caption\":\"danselibremalkovsky.com\"},\"image\":{\"@id\":\"https:\\\/\\\/danselibremalkovsky.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'oiseau - en sautant dans la corde - danselibremalkovsky.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/danselibremalkovsky.com\/es\/exercice\/loiseau-en-sautant-dans-la-corde\/","og_locale":"es_ES","og_type":"article","og_title":"L'oiseau - en sautant dans la corde - danselibremalkovsky.com","og_url":"https:\/\/danselibremalkovsky.com\/es\/exercice\/loiseau-en-sautant-dans-la-corde\/","og_site_name":"danselibremalkovsky.com","article_modified_time":"2025-02-20T10:43:04+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/12\/L_oiseau-en-sautant-dans-la-corde.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/","url":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/","name":"L'oiseau - en sautant dans la corde - danselibremalkovsky.com","isPartOf":{"@id":"https:\/\/danselibremalkovsky.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/#primaryimage"},"image":{"@id":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/#primaryimage"},"thumbnailUrl":"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/12\/L_oiseau-en-sautant-dans-la-corde.png","datePublished":"2024-12-03T13:25:37+00:00","dateModified":"2025-02-20T10:43:04+00:00","breadcrumb":{"@id":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/#primaryimage","url":"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/12\/L_oiseau-en-sautant-dans-la-corde.png","contentUrl":"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/12\/L_oiseau-en-sautant-dans-la-corde.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/danselibremalkovsky.com\/exercice\/loiseau-en-sautant-dans-la-corde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/danselibremalkovsky.com\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;oiseau &#8211; en sautant dans la corde"}]},{"@type":"WebSite","@id":"https:\/\/danselibremalkovsky.com\/#website","url":"https:\/\/danselibremalkovsky.com\/","name":"danselibremalkovsky.com","description":"&quot;Entrez dans la danse...&quot;","publisher":{"@id":"https:\/\/danselibremalkovsky.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/danselibremalkovsky.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/danselibremalkovsky.com\/#organization","name":"danselibremalkovsky.com","url":"https:\/\/danselibremalkovsky.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/danselibremalkovsky.com\/#\/schema\/logo\/image\/","url":"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/10\/cropped-Callian_logo.png","contentUrl":"https:\/\/danselibremalkovsky.com\/wp-content\/uploads\/2024\/10\/cropped-Callian_logo.png","width":1406,"height":1685,"caption":"danselibremalkovsky.com"},"image":{"@id":"https:\/\/danselibremalkovsky.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/danselibremalkovsky.com\/es\/wp-json\/wp\/v2\/exercice\/1539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danselibremalkovsky.com\/es\/wp-json\/wp\/v2\/exercice"}],"about":[{"href":"https:\/\/danselibremalkovsky.com\/es\/wp-json\/wp\/v2\/types\/exercice"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/danselibremalkovsky.com\/es\/wp-json\/wp\/v2\/media\/1541"}],"wp:attachment":[{"href":"https:\/\/danselibremalkovsky.com\/es\/wp-json\/wp\/v2\/media?parent=1539"}],"wp:term":[{"taxonomy":"categorie","embeddable":true,"href":"https:\/\/danselibremalkovsky.com\/es\/wp-json\/wp\/v2\/categorie?post=1539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}